{"id":5514,"date":"2022-11-04T15:15:39","date_gmt":"2022-11-04T15:15:39","guid":{"rendered":"https:\/\/www.fallbrookmedicalcenter.com\/?page_id=5514"},"modified":"2025-11-10T22:16:59","modified_gmt":"2025-11-10T22:16:59","slug":"cuidado-de-adultos-mayores","status":"publish","type":"page","link":"https:\/\/www.fallbrookmedicalcenter.com\/es\/cuidado-de-adultos-mayores\/","title":{"rendered":"Cuidado de adultos mayores"},"content":{"rendered":"<p><section id=\"bt_section6a580ef3c1013\"  class=\"boldSection inherit\" ><div class=\"port\"><div class=\"boldCell\"><div class=\"boldCellInner\"><div class=\"boldRow  \" ><div class=\"boldRowInner\"><div class=\"rowItem col-md-12 col-ms-12  btTextLeft\"  ><div class=\"rowItemContent\" ><div class=\"bpgPhoto \"  style=\"btTextCenter btSimpleHoverType\">\r\n\t\t\t\t\t<a href=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2022\/12\/banner-senior-care-copia.webp\" target=\"\" title=\"\"><\/a>\r\n\t\t\t\t\t<div class=\"boldPhotoBox\"><div class=\"bpbItem\"><div class=\"btImage\"><img decoding=\"async\" src=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2022\/12\/banner-senior-care-copia.webp\" alt=\"\" title=\"\"><\/div><\/div><\/div>\r\n\t\t\t\t\t<div class=\"captionPane\">\r\n\t\t\t\t\t\t<div class=\"captionTable\">\r\n\t\t\t\t\t\t\t<div class=\"captionCell\">\r\n\t\t\t\t\t\t\t\t<div class=\"captionTxt\"><header class=\"header btClear small btDash bottomDash btAlternateDash\" ><div class=\"btSubTitle\">full<\/div><\/header><\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section id=\"bt_section6a580ef3c16a8\"  class=\"boldSection topSpaced bottomSpaced gutter inherit\" ><div class=\"port\"><div class=\"boldCell\"><div class=\"boldCellInner\"><div class=\"boldRow  \" ><div class=\"boldRowInner\"><div class=\"rowItem col-md-12 col-ms-12  btTextLeft inherit\"  ><div class=\"rowItemContent\" ><div class=\"btText\" ><\/p>\n<h1 style=\"text-align: center; color: #29345d; font-size: 40px;\">PROGRAMA DE MEDICARE PARA EL CUIDADO DE PERSONAS MAYORES<\/h1>\n<h2 style=\"text-align: center; color: #29345d; font-size: 32px;\">SEA PARTE DE NUESTRA COMUNIDAD MEDICARE<br \/>\nY DISFRUTE DE ESTOS BENEFICIOS:<\/h2>\n<p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"boldRow  \" ><div class=\"boldRowInner\"><\/div><\/div><\/div><\/div><\/div><\/section><section id=\"bt_section6a580ef3c358c\"  class=\"boldSection bottomSpaced gutter inherit\" ><div class=\"port\"><div class=\"boldCell\"><div class=\"boldCellInner\"><div class=\"boldRow  \" ><div class=\"boldRowInner\"><div class=\"rowItem col-md-3 col-sm-6 col-ms-12 btTextCenter inherit btDoublePadding\"  ><div class=\"rowItemContent\" style = \"background-color:rgb(41,52,93);\"><div class=\"btClear btSeparator topSemiSpaced noBorder\" ><hr><\/div><div class=\"bpgPhoto \"  style=\"btTextCenter\">\r\n\t\t\t\t\t<a href=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2022\/10\/icon-1.webp\" target=\"\" title=\"\"><\/a>\r\n\t\t\t\t\t<div class=\"boldPhotoBox\"><div class=\"bpbItem\"><div class=\"btImage\"><img decoding=\"async\" src=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2022\/10\/icon-1.webp\" alt=\"\" title=\"\"><\/div><\/div><\/div>\r\n\t\t\t\t\t<div class=\"captionPane\">\r\n\t\t\t\t\t\t<div class=\"captionTable\">\r\n\t\t\t\t\t\t\t<div class=\"captionCell\">\r\n\t\t\t\t\t\t\t\t<div class=\"captionTxt\"><header class=\"header btClear small btDash bottomDash btAlternateDash\" ><div class=\"btSubTitle\">full<\/div><\/header><\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div><\/div><div class=\"btText\" ><\/p>\n<h3 style=\"text-align: center; color: #ffffff;\">Citas por Videollamada<\/h3>\n<p>\n<\/div><a href=\"#special-fmc-perks\" class=\"btBtn btBtn btnFilledStyle btnLightColor btnExtraSmall btnFullWidth btnRightPosition btnNoIcon\" ><span class=\"btnInnerText\">Aprende m\u00e1s<\/span><\/a><div class=\"btClear btSeparator topSemiSpaced noBorder\" ><hr><\/div><\/div><\/div><div class=\"rowItem col-md-3 col-sm-6 col-ms-12 btTextCenter inherit btDoublePadding\"  ><div class=\"rowItemContent\" style = \"background-color:rgb(54,136,176);\"><div class=\"btClear btSeparator topSemiSpaced noBorder\" ><hr><\/div><div class=\"bpgPhoto \"  style=\"btTextCenter\">\r\n\t\t\t\t\t<a href=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2022\/10\/icon-2.webp\" target=\"\" title=\"\"><\/a>\r\n\t\t\t\t\t<div class=\"boldPhotoBox\"><div class=\"bpbItem\"><div class=\"btImage\"><img decoding=\"async\" src=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2022\/10\/icon-2.webp\" alt=\"\" title=\"\"><\/div><\/div><\/div>\r\n\t\t\t\t\t<div class=\"captionPane\">\r\n\t\t\t\t\t\t<div class=\"captionTable\">\r\n\t\t\t\t\t\t\t<div class=\"captionCell\">\r\n\t\t\t\t\t\t\t\t<div class=\"captionTxt\"><header class=\"header btClear small btDash bottomDash btAlternateDash\" ><div class=\"btSubTitle\">full<\/div><\/header><\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div><\/div><div class=\"btText\" ><\/p>\n<h3 style=\"text-align: center; color: #ffffff;\">Servicio Personalizo<\/h3>\n<p>\n<\/div><a href=\"#personalized-service\" class=\"btBtn btBtn btnFilledStyle btnLightColor btnExtraSmall btnFullWidth btnRightPosition btnNoIcon\" ><span class=\"btnInnerText\">Aprende m\u00e1s<\/span><\/a><div class=\"btClear btSeparator topSemiSpaced noBorder\" ><hr><\/div><\/div><\/div><div class=\"rowItem col-md-3 col-sm-6 col-ms-12 btTextCenter inherit btDoublePadding\"  ><div class=\"rowItemContent\" style = \"background-color:rgb(146,146,146);\"><div class=\"btClear btSeparator topSemiSpaced noBorder\" ><hr><\/div><div class=\"bpgPhoto \"  style=\"btTextCenter\">\r\n\t\t\t\t\t<a href=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2022\/10\/icon-3.webp\" target=\"\" title=\"\"><\/a>\r\n\t\t\t\t\t<div class=\"boldPhotoBox\"><div class=\"bpbItem\"><div class=\"btImage\"><img decoding=\"async\" src=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2022\/10\/icon-3.webp\" alt=\"\" title=\"\"><\/div><\/div><\/div>\r\n\t\t\t\t\t<div class=\"captionPane\">\r\n\t\t\t\t\t\t<div class=\"captionTable\">\r\n\t\t\t\t\t\t\t<div class=\"captionCell\">\r\n\t\t\t\t\t\t\t\t<div class=\"captionTxt\"><header class=\"header btClear small btDash bottomDash btAlternateDash\" ><div class=\"btSubTitle\">full<\/div><\/header><\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div><\/div><div class=\"btText\" ><\/p>\n<h3 style=\"text-align: center; color: #ffffff;\">Recursos<br \/>\n<span style=\"font-weight: 400;\"><br \/>\n<\/span><\/h3>\n<p>\n<\/div><a href=\"#resources\" class=\"btBtn btBtn btnFilledStyle btnLightColor btnExtraSmall btnFullWidth btnRightPosition btnNoIcon\" ><span class=\"btnInnerText\">Aprende m\u00e1s<\/span><\/a><div class=\"btClear btSeparator topSemiSpaced noBorder\" ><hr><\/div><\/div><\/div><div class=\"rowItem col-md-3 col-sm-6 col-ms-12 btTextCenter inherit btDoublePadding\"  ><div class=\"rowItemContent\" style = \"background-color:rgb(57,57,57);\"><div class=\"btClear btSeparator topSemiSpaced noBorder\" ><hr><\/div><div class=\"bpgPhoto \"  style=\"btTextCenter\">\r\n\t\t\t\t\t<a href=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2022\/10\/icon-4.webp\" target=\"\" title=\"\"><\/a>\r\n\t\t\t\t\t<div class=\"boldPhotoBox\"><div class=\"bpbItem\"><div class=\"btImage\"><img decoding=\"async\" src=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2022\/10\/icon-4.webp\" alt=\"\" title=\"\"><\/div><\/div><\/div>\r\n\t\t\t\t\t<div class=\"captionPane\">\r\n\t\t\t\t\t\t<div class=\"captionTable\">\r\n\t\t\t\t\t\t\t<div class=\"captionCell\">\r\n\t\t\t\t\t\t\t\t<div class=\"captionTxt\"><header class=\"header btClear small btDash bottomDash btAlternateDash\" ><div class=\"btSubTitle\">full<\/div><\/header><\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div><\/div><div class=\"btText\" ><\/p>\n<h3 style=\"text-align: center; color: #ffffff;\">Eventos dise\u00f1ados para personas mayores<\/h3>\n<p>\n<\/div><a href=\"#recurrent-events\" class=\"btBtn btBtn btnFilledStyle btnLightColor btnExtraSmall btnFullWidth btnRightPosition btnNoIcon\" ><span class=\"btnInnerText\">Aprende m\u00e1s<\/span><\/a><div class=\"btClear btSeparator topSemiSpaced noBorder\" ><hr><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section id=\"how-to-become-a-patient\"  class=\"boldSection gutter inherit\" ><div class=\"port\"><div class=\"boldCell\"><div class=\"boldCellInner\"><div class=\"boldRow  \" ><div class=\"boldRowInner\"><div class=\"rowItem col-md-6 col-sm-12 btTextLeft inherit btNoPadding\"  ><div class=\"rowItemContent\" ><div class=\"bpgPhoto \"  style=\"btTextCenter\">\r\n\t\t\t\t\t<a href=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2022\/12\/how-to-become-a-patient.webp\" target=\"\" title=\"\"><\/a>\r\n\t\t\t\t\t<div class=\"boldPhotoBox\"><div class=\"bpbItem\"><div class=\"btImage\"><img decoding=\"async\" src=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2022\/12\/how-to-become-a-patient.webp\" alt=\"\" title=\"\"><\/div><\/div><\/div>\r\n\t\t\t\t\t<div class=\"captionPane\">\r\n\t\t\t\t\t\t<div class=\"captionTable\">\r\n\t\t\t\t\t\t\t<div class=\"captionCell\">\r\n\t\t\t\t\t\t\t\t<div class=\"captionTxt\"><header class=\"header btClear small btDash bottomDash btAlternateDash\" ><div class=\"btSubTitle\">full<\/div><\/header><\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div><\/div><\/div><\/div><div class=\"rowItem col-md-6 col-sm-12 btTextLeft btMiddleVertical btDoublePadding\"  ><div class=\"rowItemContent\" ><div class=\"btText\" ><\/p>\n<h2 style=\"color: #29345d;\">\u00bfC\u00d3MO CONVERTIRSE EN PACIENTE?<\/h2>\n<p>Convi\u00e9rtete en paciente<\/p>\n<p>Si quieres disfrutar de esta gran experiencia, ser nuestro paciente y no sabes por d\u00f3nde empezar, no lo dudes y contacta a nuestros representantes, quienes te guiar\u00e1n paso a paso y te acompa\u00f1ar\u00e1n de la mano en este proceso.<\/p>\n<p>Comun\u00edquese con nuestros especialistas en relaciones con los pacientes para convertirse en paciente:<\/p>\n<p>Victoria Navarro: <a class=\"c-link\" href=\"tel:7606956742\" target=\"_blank\" rel=\"noopener noreferrer\" data-stringify-link=\"tel:7606956742\" data-sk=\"tooltip_parent\">(760) 695-6742<\/a> Ext: 560<br \/>\nCorreo electr\u00f3nico: support@fallbrookmedicalcenter.com<\/p>\n<p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"boldRow  \" ><div class=\"boldRowInner\"><div class=\"rowItem col-md-12 col-ms-12  btTextLeft inherit btNoPadding\"  ><div class=\"rowItemContent\" ><div class=\"btClear btSeparator topSpaced bottomSpaced border\" ><hr><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section id=\"bt_section6a580ef3ce00e\"  class=\"boldSection gutter inherit\" ><div class=\"port\"><div class=\"boldCell\"><div class=\"boldCellInner\"><div class=\"boldRow  \" ><div class=\"boldRowInner\"><div class=\"rowItem col-md-12 col-ms-12  btTextLeft inherit btNoPadding\"  ><div class=\"rowItemContent\" ><style type=\"text\/css\">\n\t.slider-body{\n\t\talign-items: center;\n\t\tjustify-content: center;\n\t}\n\t@keyframes scroll{\n\t\t0%{\n\t\t\ttransform: translateX(0);\n\t\t}\n\t\t100%{\n\t\t\ttransform: translateX(calc(-250px *7));\n\t\t}\n\t}\n\t.slider-accepted{\n\t\tmargin: auto;\n\t\toverflow: hidden;\n\t\tposition: relative;\n\t\twidth: auto;\n\t}\n\t.slider-accepted .slider-track-accepted{\n\t\tanimation: scroll 40s linear infinite;\n\t\tdisplay: flex;\n    align-items: center;\n\t\twidth: calc(250px * 12);\n\t}\n\t.slider-accepted .slide-accepted{\n\t\twidth: 250px;\n\t}\n<\/style>\n<div class=\"slider-body\">\n<div class=\"slider-accepted\">\n\t<div class=\"slider-track-accepted\">\n\t\t<div class=\"slide-accepted\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2022\/11\/Home-logos_05.jpg\" width=\"250\" alt=\"Community health group\"\/>\n\t\t<\/div>\n\t\t<div class=\"slide-accepted\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2022\/11\/Home-logos_07.jpg\" width=\"250\" alt=\"Primary Care of Associates Group\"\/>\n\t\t<\/div>\n\t\t<div class=\"slide-accepted\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2022\/11\/Home-logos_10.jpg\" width=\"250\" alt=\"Molina Healthcare\"\/>\n\t\t<\/div>\n\t\t<div class=\"slide-accepted\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2022\/11\/Home-logos_13.jpg\" width=\"250\" alt=\"Humana\"\/>\n\t\t<\/div>\n\t\t<div class=\"slide-accepted\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2022\/11\/Home-logos_21.jpg\" width=\"250\" alt=\"Health Net\"\/>\n\t\t<\/div>\n\t\t<div class=\"slide-accepted\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2022\/11\/Home-logos_26.jpg\" width=\"250\" alt=\"Unit Health Care\"\/>\n\t\t<\/div>\n\t\t<div class=\"slide-accepted\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2022\/11\/Home-logos_28.jpg\" width=\"250\" alt=\"Redigal Medical Group\"\/>\n\t\t<\/div>\n\t\t<div class=\"slide-accepted\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2022\/11\/Home-logos_39.jpg\" width=\"250\" alt=\"Medi - cal\"\/>\n\t\t<\/div>\n\t\t<div class=\"slide-accepted\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2022\/11\/Home-logos_41.jpg\" width=\"250\" alt=\"TRICARE\"\/>\n\t\t<\/div>\n\t\t<div class=\"slide-accepted\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2022\/11\/Home-logos_43.jpg\" width=\"250\" alt=\"Blue Cross \/ Blue shield.\"\/>\n\t\t<\/div>\n\t\t<div class=\"slide-accepted\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2022\/11\/Home-logos_50.jpg\" width=\"250\" alt=\"Cigna\"\/>\n\t\t<\/div>\n\t\t<div class=\"slide-accepted\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2022\/11\/Home-logos_03.jpg\" width=\"250\" alt=\"IE HP\"\/>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div><div class=\"btText\" ><\/p>\n<h3 style=\"text-align: center;\">\u201c\u00bfNo ve su plan de salud? No se preocupe.<br \/>\nTrabajamos con numerosos planes de salud.<br \/>\nComun\u00edquese con nosotros al <span style=\"color: #003366;\"><a style=\"color: #003366;\" href=\"tel:760723900\"><strong>760-723-900<\/strong><\/a><\/span> para que podamos verificarlo o ayudarlo\u201d.<\/h3>\n<p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"boldRow  \" ><div class=\"boldRowInner\"><div class=\"rowItem col-md-12 col-ms-12  btTextLeft inherit btNoPadding\"  ><div class=\"rowItemContent\" ><div class=\"btClear btSeparator topSpaced bottomSpaced border\" ><hr><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section id=\"special-fmc-perks\"  class=\"boldSection gutter inherit\" ><div class=\"port\"><div class=\"boldCell\"><div class=\"boldCellInner\"><div class=\"boldRow  \" ><div class=\"boldRowInner\"><div class=\"rowItem col-md-6 col-sm-12 btTextLeft btMiddleVertical btDoublePadding\"  ><div class=\"rowItemContent\" ><div class=\"bpgPhoto \"  style=\"btTextCenter\">\r\n\t\t\t\t\t<a href=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2022\/11\/ttl-Special-FMC-Perks.png\" target=\"\" title=\"\"><\/a>\r\n\t\t\t\t\t<div class=\"boldPhotoBox\"><div class=\"bpbItem\"><div class=\"btImage\"><img decoding=\"async\" src=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2022\/11\/ttl-Special-FMC-Perks.png\" alt=\"\" title=\"\"><\/div><\/div><\/div>\r\n\t\t\t\t\t<div class=\"captionPane\">\r\n\t\t\t\t\t\t<div class=\"captionTable\">\r\n\t\t\t\t\t\t\t<div class=\"captionCell\">\r\n\t\t\t\t\t\t\t\t<div class=\"captionTxt\"><\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div><\/div><div class=\"btText\" ><\/p>\n<p>Cuidarse en FMC es gratificante. Nos pondremos en contacto con usted para desearle un feliz cumplea\u00f1os en su d\u00eda especial, darle la bienvenida a su primera cita, darle un obsequio en su examen anual de bienestar y mucho m\u00e1s.<\/p>\n<ol>\n<li>El mensaje de cumplea\u00f1os<\/li>\n<li>Visita anual de bienestar Regalo<\/li>\n<li>Saludos por las fiestas m\u00e1s importantes<\/li>\n<li>La carta de bienvenida<\/li>\n<li>Descuentos especiales para servicios en sitio<\/li>\n<li>Evaluaci\u00f3n de Salud Integral y Hol\u00edstica GRATIS por \u00fanica vez de 15 minutos.<\/li>\n<\/ol>\n<p>\n<\/div><div class=\"btClear btSeparator topSemiSpaced noBorder\" ><hr><\/div><\/div><\/div><div class=\"rowItem col-md-6 col-sm-12 btTextLeft btMiddleVertical btNoPadding\"  ><div class=\"rowItemContent\" ><div class=\"bpgPhoto Medical Services Fall Brook Medical Center - Because Your Health Matters\"  style=\"btTextCenter\">\r\n\t\t\t\t\t<a href=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2023\/08\/Medical-Services-Fall-Brook-Medical-Center-Because-Your-Health-Matters.webp\" target=\"\" title=\"\"><\/a>\r\n\t\t\t\t\t<div class=\"boldPhotoBox\"><div class=\"bpbItem\"><div class=\"btImage\"><img decoding=\"async\" src=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2023\/08\/Medical-Services-Fall-Brook-Medical-Center-Because-Your-Health-Matters.webp\" alt=\"\" title=\"\"><\/div><\/div><\/div>\r\n\t\t\t\t\t<div class=\"captionPane\">\r\n\t\t\t\t\t\t<div class=\"captionTable\">\r\n\t\t\t\t\t\t\t<div class=\"captionCell\">\r\n\t\t\t\t\t\t\t\t<div class=\"captionTxt\"><header class=\"header btClear small btDash bottomDash btAlternateDash\" ><div class=\"btSubTitle\">full<\/div><\/header><\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"boldRow  \" ><div class=\"boldRowInner\"><div class=\"rowItem col-md-12 col-ms-12  btTextLeft inherit btNoPadding\"  ><div class=\"rowItemContent\" ><div class=\"btClear btSeparator topSpaced bottomSpaced border\" ><hr><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section id=\"personalized-service\"  class=\"boldSection gutter inherit\" ><div class=\"port\"><div class=\"boldCell\"><div class=\"boldCellInner\"><div class=\"boldRow  \" ><div class=\"boldRowInner\"><div class=\"rowItem col-md-6 col-sm-12 btTextLeft\"  ><div class=\"rowItemContent\" ><div class=\"bpgPhoto \"  style=\"btTextCenter\">\r\n\t\t\t\t\t<a href=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2022\/11\/personalized-service-1.webp\" target=\"\" title=\"\"><\/a>\r\n\t\t\t\t\t<div class=\"boldPhotoBox\"><div class=\"bpbItem\"><div class=\"btImage\"><img decoding=\"async\" src=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2022\/11\/personalized-service-1.webp\" alt=\"\" title=\"\"><\/div><\/div><\/div>\r\n\t\t\t\t\t<div class=\"captionPane\">\r\n\t\t\t\t\t\t<div class=\"captionTable\">\r\n\t\t\t\t\t\t\t<div class=\"captionCell\">\r\n\t\t\t\t\t\t\t\t<div class=\"captionTxt\"><header class=\"header btClear small btDash bottomDash btAlternateDash\" ><div class=\"btSubTitle\">full<\/div><\/header><\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div><\/div><\/div><\/div><div class=\"rowItem col-md-6 col-sm-12 btTextLeft btMiddleVertical btDoublePadding\"  ><div class=\"rowItemContent\" ><div class=\"bpgPhoto \"  style=\"btTextCenter\">\r\n\t\t\t\t\t<a href=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2022\/11\/ttl-Personalized-Service.png\" target=\"\" title=\"\"><\/a>\r\n\t\t\t\t\t<div class=\"boldPhotoBox\"><div class=\"bpbItem\"><div class=\"btImage\"><img decoding=\"async\" src=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2022\/11\/ttl-Personalized-Service.png\" alt=\"\" title=\"\"><\/div><\/div><\/div>\r\n\t\t\t\t\t<div class=\"captionPane\">\r\n\t\t\t\t\t\t<div class=\"captionTable\">\r\n\t\t\t\t\t\t\t<div class=\"captionCell\">\r\n\t\t\t\t\t\t\t\t<div class=\"captionTxt\"><\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div><\/div><div class=\"btText\" ><\/p>\n<p>Cuando usted se convierte en paciente de Fallbrook Medical Center, disfrutar\u00e1 de grandes beneficios que incluyen nuestros conocidos recordatorios de citas, recordatorios para sus otros ex\u00e1menes preventivos, lectura telef\u00f3nica de resultados de laboratorio, notificaci\u00f3n de referencias realizadas, etc.<\/p>\n<ol>\n<li>Recordatorio personalizado para an\u00e1lisis de laboratorio y citas.<\/li>\n<li>Lectura de resultados de pruebas por tel\u00e9fono<\/li>\n<li>Seguimiento despu\u00e9s de las citas<\/li>\n<li>Derivaciones a especialistas, pruebas y ex\u00e1menes complementarios.<\/li>\n<\/ol>\n<p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"boldRow  \" ><div class=\"boldRowInner\"><div class=\"rowItem col-md-12 col-ms-12  btTextLeft\"  ><div class=\"rowItemContent\" ><div class=\"btClear btSeparator topSpaced bottomSpaced border\" ><hr><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section id=\"resources\"  class=\"boldSection gutter inherit\" ><div class=\"port\"><div class=\"boldCell\"><div class=\"boldCellInner\"><div class=\"boldRow  \" ><div class=\"boldRowInner\"><div class=\"rowItem col-md-6 col-sm-12 btTextLeft btMiddleVertical\"  ><div class=\"rowItemContent\" ><div class=\"bpgPhoto \"  style=\"btTextCenter\">\r\n\t\t\t\t\t<a href=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2022\/11\/ttl-resources.png\" target=\"\" title=\"\"><\/a>\r\n\t\t\t\t\t<div class=\"boldPhotoBox\"><div class=\"bpbItem\"><div class=\"btImage\"><img decoding=\"async\" src=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2022\/11\/ttl-resources.png\" alt=\"\" title=\"\"><\/div><\/div><\/div>\r\n\t\t\t\t\t<div class=\"captionPane\">\r\n\t\t\t\t\t\t<div class=\"captionTable\">\r\n\t\t\t\t\t\t\t<div class=\"captionCell\">\r\n\t\t\t\t\t\t\t\t<div class=\"captionTxt\"><\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div><\/div><div class=\"btText\" ><\/p>\n<p>Nuestro objetivo es brindar la mejor calidad de atenci\u00f3n y beneficios. Algunos de nuestros recursos incluyen: Mensaje a su m\u00e9dico, l\u00ednea directa para consultas de adultos mayores, personal que habla espa\u00f1ol y m\u00e1s.<\/p>\n<ol>\n<li>Env\u00edale un mensaje a tu m\u00e9dico<\/li>\n<li>L\u00ednea directa para pacientes de Medicare<\/li>\n<li>Uso del idioma espa\u00f1ol<\/li>\n<li>Citas por videollamada.<\/li>\n<\/ol>\n<p><br style=\"font-weight: 400;\" \/><br style=\"font-weight: 400;\" \/><\/p>\n<p>\n<\/div><\/div><\/div><div class=\"rowItem col-md-6 col-sm-12 btTextLeft\"  ><div class=\"rowItemContent\" ><div class=\"bpgPhoto \"  style=\"btTextCenter\">\r\n\t\t\t\t\t<a href=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2022\/11\/resources-1.webp\" target=\"\" title=\"\"><\/a>\r\n\t\t\t\t\t<div class=\"boldPhotoBox\"><div class=\"bpbItem\"><div class=\"btImage\"><img decoding=\"async\" src=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2022\/11\/resources-1.webp\" alt=\"\" title=\"\"><\/div><\/div><\/div>\r\n\t\t\t\t\t<div class=\"captionPane\">\r\n\t\t\t\t\t\t<div class=\"captionTable\">\r\n\t\t\t\t\t\t\t<div class=\"captionCell\">\r\n\t\t\t\t\t\t\t\t<div class=\"captionTxt\"><header class=\"header btClear small btDash bottomDash btAlternateDash\" ><div class=\"btSubTitle\">full<\/div><\/header><\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"boldRow  \" ><div class=\"boldRowInner\"><div class=\"rowItem col-md-12 col-ms-12  btTextLeft\"  ><div class=\"rowItemContent\" ><div class=\"btClear btSeparator topSpaced bottomSpaced border\" ><hr><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section id=\"recurrent-events\"  class=\"boldSection gutter inherit\" ><div class=\"port\"><div class=\"boldCell\"><div class=\"boldCellInner\"><div class=\"boldRow  \" ><div class=\"boldRowInner\"><div class=\"rowItem col-md-6 col-sm-12 btTextLeft\"  ><div class=\"rowItemContent\" ><div class=\"bpgPhoto \"  style=\"btTextCenter\">\r\n\t\t\t\t\t<a href=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2022\/12\/recurrent-events.webp\" target=\"\" title=\"\"><\/a>\r\n\t\t\t\t\t<div class=\"boldPhotoBox\"><div class=\"bpbItem\"><div class=\"btImage\"><img decoding=\"async\" src=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2022\/12\/recurrent-events.webp\" alt=\"\" title=\"\"><\/div><\/div><\/div>\r\n\t\t\t\t\t<div class=\"captionPane\">\r\n\t\t\t\t\t\t<div class=\"captionTable\">\r\n\t\t\t\t\t\t\t<div class=\"captionCell\">\r\n\t\t\t\t\t\t\t\t<div class=\"captionTxt\"><header class=\"header btClear small btDash bottomDash btAlternateDash\" ><div class=\"btSubTitle\">full<\/div><\/header><\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div><\/div><div class=\"btClear btSeparator topSpaced noBorder\" ><hr><\/div><\/div><\/div><div class=\"rowItem col-md-6 col-sm-12 btTextLeft btMiddleVertical btDoublePadding\"  ><div class=\"rowItemContent\" ><div class=\"bpgPhoto \"  style=\"btTextCenter\">\r\n\t\t\t\t\t<a href=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2022\/11\/ttl-recurrent-events.png\" target=\"\" title=\"\"><\/a>\r\n\t\t\t\t\t<div class=\"boldPhotoBox\"><div class=\"bpbItem\"><div class=\"btImage\"><img decoding=\"async\" src=\"https:\/\/www.fallbrookmedicalcenter.com\/wp-content\/uploads\/2022\/11\/ttl-recurrent-events.png\" alt=\"\" title=\"\"><\/div><\/div><\/div>\r\n\t\t\t\t\t<div class=\"captionPane\">\r\n\t\t\t\t\t\t<div class=\"captionTable\">\r\n\t\t\t\t\t\t\t<div class=\"captionCell\">\r\n\t\t\t\t\t\t\t\t<div class=\"captionTxt\"><\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div><\/div><div class=\"btText\" ><\/p>\n<p>Siempre nos aseguramos de que disfrutes de nuestros servicios. Convertirte en un paciente mayor de FMC te permitir\u00e1 tener eventos donde podr\u00e1s conocer a tus m\u00e9dicos, compartir momentos con nuestro personal, conocer a los fundadores de la cl\u00ednica y muchas actividades m\u00e1s.<\/p>\n<ol>\n<li>Reuniones peri\u00f3dicas en el lugar para personas mayores<\/li>\n<li>Eventos en residencias para mayores.<\/li>\n<\/ol>\n<p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section id=\"bt_section6a580ef3d0fd4\"  class=\"boldSection gutter\" ><div class=\"port\"><div class=\"boldCell\"><div class=\"boldCellInner\"><\/div><\/div><\/div><\/section><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-5514","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cuidado de adultos mayores - Fallbrook Medical Center<\/title>\n<meta name=\"description\" content=\"Programa de medicare para el cuidado de personas mayores y sea parte de nuestra comunidad medicare y disfrute de estos beneficios\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fallbrookmedicalcenter.com\/senior-care\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cuidado de adultos mayores - Fallbrook Medical Center\" \/>\n<meta property=\"og:description\" content=\"Programa de medicare para el cuidado de personas mayores y sea parte de nuestra comunidad medicare y disfrute de estos beneficios\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fallbrookmedicalcenter.com\/senior-care\/\" \/>\n<meta property=\"og:site_name\" content=\"Fallbrook Medical Center\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/FallbrookMedical\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-10T22:16:59+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@fallbrookmed\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"15 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fallbrookmedicalcenter.com\/senior-care\/\",\"url\":\"https:\/\/www.fallbrookmedicalcenter.com\/senior-care\/\",\"name\":\"Cuidado de adultos mayores - Fallbrook Medical Center\",\"isPartOf\":{\"@id\":\"https:\/\/www.fallbrookmedicalcenter.com\/#website\"},\"datePublished\":\"2022-11-04T15:15:39+00:00\",\"dateModified\":\"2025-11-10T22:16:59+00:00\",\"description\":\"Programa de medicare para el cuidado de personas mayores y sea parte de nuestra comunidad medicare y disfrute de estos beneficios\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fallbrookmedicalcenter.com\/senior-care\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fallbrookmedicalcenter.com\/senior-care\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fallbrookmedicalcenter.com\/senior-care\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.fallbrookmedicalcenter.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cuidado de adultos mayores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fallbrookmedicalcenter.com\/#website\",\"url\":\"https:\/\/www.fallbrookmedicalcenter.com\/\",\"name\":\"Fallbrook Medical Center\",\"description\":\"Por que tu Salud Importa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fallbrookmedicalcenter.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cuidado de adultos mayores - Fallbrook Medical Center","description":"Programa de medicare para el cuidado de personas mayores y sea parte de nuestra comunidad medicare y disfrute de estos beneficios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fallbrookmedicalcenter.com\/senior-care\/","og_locale":"es_ES","og_type":"article","og_title":"Cuidado de adultos mayores - Fallbrook Medical Center","og_description":"Programa de medicare para el cuidado de personas mayores y sea parte de nuestra comunidad medicare y disfrute de estos beneficios","og_url":"https:\/\/www.fallbrookmedicalcenter.com\/senior-care\/","og_site_name":"Fallbrook Medical Center","article_publisher":"http:\/\/www.facebook.com\/FallbrookMedical","article_modified_time":"2025-11-10T22:16:59+00:00","twitter_card":"summary_large_image","twitter_site":"@fallbrookmed","twitter_misc":{"Est. reading time":"15 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fallbrookmedicalcenter.com\/senior-care\/","url":"https:\/\/www.fallbrookmedicalcenter.com\/senior-care\/","name":"Cuidado de adultos mayores - Fallbrook Medical Center","isPartOf":{"@id":"https:\/\/www.fallbrookmedicalcenter.com\/#website"},"datePublished":"2022-11-04T15:15:39+00:00","dateModified":"2025-11-10T22:16:59+00:00","description":"Programa de medicare para el cuidado de personas mayores y sea parte de nuestra comunidad medicare y disfrute de estos beneficios","breadcrumb":{"@id":"https:\/\/www.fallbrookmedicalcenter.com\/senior-care\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fallbrookmedicalcenter.com\/senior-care\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fallbrookmedicalcenter.com\/senior-care\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.fallbrookmedicalcenter.com\/es\/"},{"@type":"ListItem","position":2,"name":"Cuidado de adultos mayores"}]},{"@type":"WebSite","@id":"https:\/\/www.fallbrookmedicalcenter.com\/#website","url":"https:\/\/www.fallbrookmedicalcenter.com\/","name":"Fallbrook Medical Center","description":"Por que tu Salud Importa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fallbrookmedicalcenter.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"}]}},"_links":{"self":[{"href":"https:\/\/www.fallbrookmedicalcenter.com\/es\/wp-json\/wp\/v2\/pages\/5514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fallbrookmedicalcenter.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.fallbrookmedicalcenter.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.fallbrookmedicalcenter.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fallbrookmedicalcenter.com\/es\/wp-json\/wp\/v2\/comments?post=5514"}],"version-history":[{"count":4,"href":"https:\/\/www.fallbrookmedicalcenter.com\/es\/wp-json\/wp\/v2\/pages\/5514\/revisions"}],"predecessor-version":[{"id":6837,"href":"https:\/\/www.fallbrookmedicalcenter.com\/es\/wp-json\/wp\/v2\/pages\/5514\/revisions\/6837"}],"wp:attachment":[{"href":"https:\/\/www.fallbrookmedicalcenter.com\/es\/wp-json\/wp\/v2\/media?parent=5514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}